{"id":129,"count":12,"description":"","link":"https:\/\/collectifmdm-idf.org\/annuaire5\/category\/scenes-du-monde-au-canal\/","name":"Sc\u00e8nes du Monde au Canal","slug":"scenes-du-monde-au-canal","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/collectifmdm-idf.org\/annuaire5\/wp-json\/wp\/v2\/categories\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/collectifmdm-idf.org\/annuaire5\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/collectifmdm-idf.org\/annuaire5\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/collectifmdm-idf.org\/annuaire5\/wp-json\/wp\/v2\/posts?categories=129"},{"href":"https:\/\/collectifmdm-idf.org\/annuaire5\/wp-json\/wp\/v2\/pages?categories=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}